{"id":3967,"date":"2023-01-20T15:30:31","date_gmt":"2023-01-20T14:30:31","guid":{"rendered":"https:\/\/mcesd.org.mt\/?p=3967"},"modified":"2023-04-14T15:55:40","modified_gmt":"2023-04-14T13:55:40","slug":"vizjoni-socjali-ghal-malta-2035","status":"publish","type":"post","link":"https:\/\/mcesd.org.mt\/mt\/vizjoni-socjali-ghal-malta-2035\/","title":{"rendered":"Vi\u017cjoni So\u010bjali g\u0127al Malta 2035"},"content":{"rendered":"<p>Fil-laqg\u0127a tal-MCESD tal-20\/1\/2023, ing\u0127atat pre\u017centazzjoni mill-Ministeru g\u0127all-\u0120ustizzja So\u010bjali u s-Solidarjet\u00e0, il-Familja u d-Drittijiet tat-Tfal biex tinforma lill-imsie\u0127ba so\u010bjali dwar il-Vi\u017cjoni So\u010bjali g\u0127al Malta 2035.<\/p>\n<p>Il-pre\u017centazzjoni tista\u2019 ti\u0121i a\u010b\u010bessata <a href=\"https:\/\/mcesd.org.mt\/wp-content\/uploads\/2023\/01\/Social-Vision-_final-presentation.pdf\">hawn<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fil-laqg\u0127a tal-MCESD tal-20\/1\/2023, ing\u0127atat pre\u017centazzjoni mill-Ministeru g\u0127all-\u0120ustizzja So\u010bjali u s-Solidarjet\u00e0, il-Familja u d-Drittijiet tat-Tfal biex tinforma lill-imsie\u0127ba so\u010bjali dwar il-Vi\u017cjoni So\u010bjali g\u0127al Malta 2035. Il-pre\u017centazzjoni tista\u2019 ti\u0121i a\u010b\u010bessata hawn.<\/p>\n","protected":false},"author":4,"featured_media":3085,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[29],"tags":[],"class_list":["post-3967","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-prezentazzjonijiet-tal-kunsill-tal-mcesd"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vi\u017cjoni So\u010bjali g\u0127al Malta 2035 - MCESD<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mcesd.org.mt\/mt\/vizjoni-socjali-ghal-malta-2035\/\" \/>\n<meta property=\"og:locale\" content=\"mt_MT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vi\u017cjoni So\u010bjali g\u0127al Malta 2035 - MCESD\" \/>\n<meta property=\"og:description\" content=\"Fil-laqg\u0127a tal-MCESD tal-20\/1\/2023, ing\u0127atat pre\u017centazzjoni mill-Ministeru g\u0127all-\u0120ustizzja So\u010bjali u s-Solidarjet\u00e0, il-Familja u d-Drittijiet tat-Tfal biex tinforma lill-imsie\u0127ba so\u010bjali dwar il-Vi\u017cjoni So\u010bjali g\u0127al Malta 2035. Il-pre\u017centazzjoni tista\u2019 ti\u0121i a\u010b\u010bessata hawn.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mcesd.org.mt\/mt\/vizjoni-socjali-ghal-malta-2035\/\" \/>\n<meta property=\"og:site_name\" content=\"MCESD\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-20T14:30:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-14T13:55:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mcesd.org.mt\/wp-content\/uploads\/2023\/01\/Social-Vision.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ray Bartolo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ray Bartolo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mcesd.org.mt\\\/mt\\\/vizjoni-socjali-ghal-malta-2035\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mcesd.org.mt\\\/mt\\\/vizjoni-socjali-ghal-malta-2035\\\/\"},\"author\":{\"name\":\"Ray Bartolo\",\"@id\":\"https:\\\/\\\/mcesd.org.mt\\\/#\\\/schema\\\/person\\\/deebed397fcbc89f02b99703ebc805ac\"},\"headline\":\"Vi\u017cjoni So\u010bjali g\u0127al Malta 2035\",\"datePublished\":\"2023-01-20T14:30:31+00:00\",\"dateModified\":\"2023-04-14T13:55:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mcesd.org.mt\\\/mt\\\/vizjoni-socjali-ghal-malta-2035\\\/\"},\"wordCount\":49,\"image\":{\"@id\":\"https:\\\/\\\/mcesd.org.mt\\\/mt\\\/vizjoni-socjali-ghal-malta-2035\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mcesd.org.mt\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Social-Vision.jpeg\",\"articleSection\":[\"Pre\u017centazzjonijiet tal-Kunsill tal-MCESD\"],\"inLanguage\":\"mt-MT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mcesd.org.mt\\\/mt\\\/vizjoni-socjali-ghal-malta-2035\\\/\",\"url\":\"https:\\\/\\\/mcesd.org.mt\\\/mt\\\/vizjoni-socjali-ghal-malta-2035\\\/\",\"name\":\"Vi\u017cjoni So\u010bjali g\u0127al Malta 2035 - MCESD\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mcesd.org.mt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mcesd.org.mt\\\/mt\\\/vizjoni-socjali-ghal-malta-2035\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mcesd.org.mt\\\/mt\\\/vizjoni-socjali-ghal-malta-2035\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mcesd.org.mt\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Social-Vision.jpeg\",\"datePublished\":\"2023-01-20T14:30:31+00:00\",\"dateModified\":\"2023-04-14T13:55:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/mcesd.org.mt\\\/#\\\/schema\\\/person\\\/deebed397fcbc89f02b99703ebc805ac\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mcesd.org.mt\\\/mt\\\/vizjoni-socjali-ghal-malta-2035\\\/#breadcrumb\"},\"inLanguage\":\"mt-MT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mcesd.org.mt\\\/mt\\\/vizjoni-socjali-ghal-malta-2035\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"mt-MT\",\"@id\":\"https:\\\/\\\/mcesd.org.mt\\\/mt\\\/vizjoni-socjali-ghal-malta-2035\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mcesd.org.mt\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Social-Vision.jpeg\",\"contentUrl\":\"https:\\\/\\\/mcesd.org.mt\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Social-Vision.jpeg\",\"width\":1600,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mcesd.org.mt\\\/mt\\\/vizjoni-socjali-ghal-malta-2035\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mcesd.org.mt\\\/mt\\\/home-page\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vi\u017cjoni So\u010bjali g\u0127al Malta 2035\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mcesd.org.mt\\\/#website\",\"url\":\"https:\\\/\\\/mcesd.org.mt\\\/\",\"name\":\"MCESD\",\"description\":\"Il-Kunsill Malti g\u0127all-I\u017cvilupp Ekonomiku u So\u010bjali\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mcesd.org.mt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"mt-MT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mcesd.org.mt\\\/#\\\/schema\\\/person\\\/deebed397fcbc89f02b99703ebc805ac\",\"name\":\"Ray Bartolo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"mt-MT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b3e7df82e957f7f248b53be145fb3bacf1d73facbc80a945798173ce3893fe71?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b3e7df82e957f7f248b53be145fb3bacf1d73facbc80a945798173ce3893fe71?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b3e7df82e957f7f248b53be145fb3bacf1d73facbc80a945798173ce3893fe71?s=96&d=mm&r=g\",\"caption\":\"Ray Bartolo\"},\"url\":\"https:\\\/\\\/mcesd.org.mt\\\/mt\\\/author\\\/ray-bartolo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vi\u017cjoni So\u010bjali g\u0127al Malta 2035 - MCESD","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mcesd.org.mt\/mt\/vizjoni-socjali-ghal-malta-2035\/","og_locale":"mt_MT","og_type":"article","og_title":"Vi\u017cjoni So\u010bjali g\u0127al Malta 2035 - MCESD","og_description":"Fil-laqg\u0127a tal-MCESD tal-20\/1\/2023, ing\u0127atat pre\u017centazzjoni mill-Ministeru g\u0127all-\u0120ustizzja So\u010bjali u s-Solidarjet\u00e0, il-Familja u d-Drittijiet tat-Tfal biex tinforma lill-imsie\u0127ba so\u010bjali dwar il-Vi\u017cjoni So\u010bjali g\u0127al Malta 2035. Il-pre\u017centazzjoni tista\u2019 ti\u0121i a\u010b\u010bessata hawn.","og_url":"https:\/\/mcesd.org.mt\/mt\/vizjoni-socjali-ghal-malta-2035\/","og_site_name":"MCESD","article_published_time":"2023-01-20T14:30:31+00:00","article_modified_time":"2023-04-14T13:55:40+00:00","og_image":[{"width":1600,"height":900,"url":"https:\/\/mcesd.org.mt\/wp-content\/uploads\/2023\/01\/Social-Vision.jpeg","type":"image\/jpeg"}],"author":"Ray Bartolo","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Ray Bartolo","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mcesd.org.mt\/mt\/vizjoni-socjali-ghal-malta-2035\/#article","isPartOf":{"@id":"https:\/\/mcesd.org.mt\/mt\/vizjoni-socjali-ghal-malta-2035\/"},"author":{"name":"Ray Bartolo","@id":"https:\/\/mcesd.org.mt\/#\/schema\/person\/deebed397fcbc89f02b99703ebc805ac"},"headline":"Vi\u017cjoni So\u010bjali g\u0127al Malta 2035","datePublished":"2023-01-20T14:30:31+00:00","dateModified":"2023-04-14T13:55:40+00:00","mainEntityOfPage":{"@id":"https:\/\/mcesd.org.mt\/mt\/vizjoni-socjali-ghal-malta-2035\/"},"wordCount":49,"image":{"@id":"https:\/\/mcesd.org.mt\/mt\/vizjoni-socjali-ghal-malta-2035\/#primaryimage"},"thumbnailUrl":"https:\/\/mcesd.org.mt\/wp-content\/uploads\/2023\/01\/Social-Vision.jpeg","articleSection":["Pre\u017centazzjonijiet tal-Kunsill tal-MCESD"],"inLanguage":"mt-MT"},{"@type":"WebPage","@id":"https:\/\/mcesd.org.mt\/mt\/vizjoni-socjali-ghal-malta-2035\/","url":"https:\/\/mcesd.org.mt\/mt\/vizjoni-socjali-ghal-malta-2035\/","name":"Vi\u017cjoni So\u010bjali g\u0127al Malta 2035 - MCESD","isPartOf":{"@id":"https:\/\/mcesd.org.mt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mcesd.org.mt\/mt\/vizjoni-socjali-ghal-malta-2035\/#primaryimage"},"image":{"@id":"https:\/\/mcesd.org.mt\/mt\/vizjoni-socjali-ghal-malta-2035\/#primaryimage"},"thumbnailUrl":"https:\/\/mcesd.org.mt\/wp-content\/uploads\/2023\/01\/Social-Vision.jpeg","datePublished":"2023-01-20T14:30:31+00:00","dateModified":"2023-04-14T13:55:40+00:00","author":{"@id":"https:\/\/mcesd.org.mt\/#\/schema\/person\/deebed397fcbc89f02b99703ebc805ac"},"breadcrumb":{"@id":"https:\/\/mcesd.org.mt\/mt\/vizjoni-socjali-ghal-malta-2035\/#breadcrumb"},"inLanguage":"mt-MT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mcesd.org.mt\/mt\/vizjoni-socjali-ghal-malta-2035\/"]}]},{"@type":"ImageObject","inLanguage":"mt-MT","@id":"https:\/\/mcesd.org.mt\/mt\/vizjoni-socjali-ghal-malta-2035\/#primaryimage","url":"https:\/\/mcesd.org.mt\/wp-content\/uploads\/2023\/01\/Social-Vision.jpeg","contentUrl":"https:\/\/mcesd.org.mt\/wp-content\/uploads\/2023\/01\/Social-Vision.jpeg","width":1600,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/mcesd.org.mt\/mt\/vizjoni-socjali-ghal-malta-2035\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mcesd.org.mt\/mt\/home-page\/"},{"@type":"ListItem","position":2,"name":"Vi\u017cjoni So\u010bjali g\u0127al Malta 2035"}]},{"@type":"WebSite","@id":"https:\/\/mcesd.org.mt\/#website","url":"https:\/\/mcesd.org.mt\/","name":"MCESD","description":"Il-Kunsill Malti g\u0127all-I\u017cvilupp Ekonomiku u So\u010bjali","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mcesd.org.mt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"mt-MT"},{"@type":"Person","@id":"https:\/\/mcesd.org.mt\/#\/schema\/person\/deebed397fcbc89f02b99703ebc805ac","name":"Ray Bartolo","image":{"@type":"ImageObject","inLanguage":"mt-MT","@id":"https:\/\/secure.gravatar.com\/avatar\/b3e7df82e957f7f248b53be145fb3bacf1d73facbc80a945798173ce3893fe71?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b3e7df82e957f7f248b53be145fb3bacf1d73facbc80a945798173ce3893fe71?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b3e7df82e957f7f248b53be145fb3bacf1d73facbc80a945798173ce3893fe71?s=96&d=mm&r=g","caption":"Ray Bartolo"},"url":"https:\/\/mcesd.org.mt\/mt\/author\/ray-bartolo\/"}]}},"_links":{"self":[{"href":"https:\/\/mcesd.org.mt\/mt\/wp-json\/wp\/v2\/posts\/3967","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mcesd.org.mt\/mt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mcesd.org.mt\/mt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mcesd.org.mt\/mt\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/mcesd.org.mt\/mt\/wp-json\/wp\/v2\/comments?post=3967"}],"version-history":[{"count":2,"href":"https:\/\/mcesd.org.mt\/mt\/wp-json\/wp\/v2\/posts\/3967\/revisions"}],"predecessor-version":[{"id":3969,"href":"https:\/\/mcesd.org.mt\/mt\/wp-json\/wp\/v2\/posts\/3967\/revisions\/3969"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mcesd.org.mt\/mt\/wp-json\/wp\/v2\/media\/3085"}],"wp:attachment":[{"href":"https:\/\/mcesd.org.mt\/mt\/wp-json\/wp\/v2\/media?parent=3967"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mcesd.org.mt\/mt\/wp-json\/wp\/v2\/categories?post=3967"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mcesd.org.mt\/mt\/wp-json\/wp\/v2\/tags?post=3967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}